{"id":6363,"date":"2022-01-27T12:22:50","date_gmt":"2022-01-27T11:22:50","guid":{"rendered":"https:\/\/elisa-willet.com\/?p=6363"},"modified":"2022-01-27T12:25:41","modified_gmt":"2022-01-27T11:25:41","slug":"le-jeune-hydrique-quest-ce-que-cest","status":"publish","type":"post","link":"https:\/\/elisa-willet.com\/index.php\/2022\/01\/27\/le-jeune-hydrique-quest-ce-que-cest\/","title":{"rendered":"Le je\u00fbne hydrique &#8211; qu&#8217;est ce que c&#8217;est"},"content":{"rendered":"<p>C\u2019est le bon moment pour faire du bien \u00e0 votre corps!<br \/>\nLa rentr\u00e9e est souvent source de stress ce qui provoque un d\u00e9s\u00e9quilibre \u00e0 votre organisme, pour cela il est bon de le r\u00e9\u00e9quilibrer par une d\u00e9tox puis par une phase de remin\u00e9ralisation afin de bien booster votre vitalit\u00e9.<br \/>\nQu\u2019est-ce que la d\u00e9tox?<br \/>\nElle a pour but de r\u00e9duire les sources de la tox\u00e9mie.<br \/>\nIl existe de nombreuses m\u00e9thodes de je\u00fbne.<br \/>\nAujourd\u2019hui, je vous parle du je\u00fbne hydrique qui consiste \u00e0 retirer tous les aliments solides de votre alimentation. La digestion est ainsi mise au repos, votre organisme se nettoie et se r\u00e9g\u00e9n\u00e8re de l\u2019int\u00e9rieur.\u270c\ud83c\udffb<br \/>\n.<br \/>\n.<br \/>\n.<br \/>\n<a class=\" xil3i\" tabindex=\"0\" href=\"https:\/\/www.instagram.com\/explore\/tags\/automne\/\">#automne<\/a>\u00a0<a class=\" xil3i\" tabindex=\"0\" href=\"https:\/\/www.instagram.com\/explore\/tags\/detoxdrink\/\">#detoxdrink<\/a>\u00a0<a class=\" xil3i\" tabindex=\"0\" href=\"https:\/\/www.instagram.com\/explore\/tags\/bienetre\/\">#bienetre<\/a>\u00a0<a class=\" xil3i\" tabindex=\"0\" href=\"https:\/\/www.instagram.com\/explore\/tags\/massage\/\">#massage<\/a>\u00a0<a class=\" xil3i\" tabindex=\"0\" href=\"https:\/\/www.instagram.com\/explore\/tags\/naturo\/\">#naturo<\/a>\u00a0<a class=\" xil3i\" tabindex=\"0\" href=\"https:\/\/www.instagram.com\/explore\/tags\/relax\/\">#relax<\/a>\u00a0<a class=\" xil3i\" tabindex=\"0\" href=\"https:\/\/www.instagram.com\/explore\/tags\/je%C3%BBne\/\">#je\u00fbne<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>C\u2019est le bon moment pour faire du bien \u00e0 votre corps! La rentr\u00e9e est souvent source de stress ce qui provoque un d\u00e9s\u00e9quilibre \u00e0 votre organisme, pour cela il est bon de le r\u00e9\u00e9quilibrer par une d\u00e9tox puis par une phase de remin\u00e9ralisation afin de bien booster votre vitalit\u00e9. Qu\u2019est-ce que la d\u00e9tox? Elle a [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[16],"tags":[],"_links":{"self":[{"href":"https:\/\/elisa-willet.com\/index.php\/wp-json\/wp\/v2\/posts\/6363"}],"collection":[{"href":"https:\/\/elisa-willet.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/elisa-willet.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/elisa-willet.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/elisa-willet.com\/index.php\/wp-json\/wp\/v2\/comments?post=6363"}],"version-history":[{"count":2,"href":"https:\/\/elisa-willet.com\/index.php\/wp-json\/wp\/v2\/posts\/6363\/revisions"}],"predecessor-version":[{"id":6365,"href":"https:\/\/elisa-willet.com\/index.php\/wp-json\/wp\/v2\/posts\/6363\/revisions\/6365"}],"wp:attachment":[{"href":"https:\/\/elisa-willet.com\/index.php\/wp-json\/wp\/v2\/media?parent=6363"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/elisa-willet.com\/index.php\/wp-json\/wp\/v2\/categories?post=6363"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/elisa-willet.com\/index.php\/wp-json\/wp\/v2\/tags?post=6363"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}